{"id":917919,"date":"2024-10-22T14:42:01","date_gmt":"2024-10-22T12:42:01","guid":{"rendered":"https:\/\/www.reersafety.com\/?page_id=917919"},"modified":"2024-10-22T15:18:15","modified_gmt":"2024-10-22T13:18:15","slug":"solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras","status":"publish","type":"page","link":"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/","title":{"rendered":"m\u00e1quinas paletizadoras e embaladoras"},"content":{"rendered":"\n<div class=\"slider-wrapper relative inner-slider-block\" id=\"slider-1928327318\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-container slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": false,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": false,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\n  <div class=\"banner has-hover inner-slider-block\" id=\"banner-2047618497\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n              <div class=\"height-fix is-invisible\"><img width=\"1920\" height=\"540\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/Leaderboard-pallettizzatore.webp\" class=\"attachment-original size-original\" alt=\"improving safety in pallet transport lines\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/Leaderboard-pallettizzatore.webp 1920w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/Leaderboard-pallettizzatore-300x84.webp 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/Leaderboard-pallettizzatore-1024x288.webp 1024w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/Leaderboard-pallettizzatore-768x216.webp 768w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/Leaderboard-pallettizzatore-1536x432.webp 1536w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/Leaderboard-pallettizzatore-510x143.webp 510w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"Leaderboard-pallettizzatore\" \/><\/div>\n            \n<style>\n#banner-2047618497 .bg.bg-loaded {\n  background-image: url(https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/Leaderboard-pallettizzatore.webp);\n}\n<\/style>\n  <\/div>\n\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n          <style>\n            #slider-1928327318 .flickity-slider > *{ max-width: 100%!important;\n     <\/style>\n     \t<\/div>\n\n\n\t<section class=\"section breadcrumb-section\" id=\"section_1197088964\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-60288226\">\n\n\n\t<div id=\"col-1784103122\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div id=\"page-header-1414869196\" class=\"page-header-wrapper\">\n  <div class=\"page-title breadcrumb light simple-title\">\n\n    \n    <div class=\"page-title-inner container align-center flex-row medium-flex-wrap row-reverse\" >\n            <div class=\"title-content flex-col flex-left text-left medium-text-center\">\n        <div class=\"title-breadcrumbs pb-half pt-half\"><nav class=\"woocommerce-breadcrumb breadcrumbs uppercase\">In\u00edcio<\/nav><\/div>      <\/div>\n    <\/div>\n\n       <\/div>\n    <\/div>\n  \n\n\n\t\t<\/div>\n\t\t\n<style>\n#col-1784103122 > .col-inner {\n  padding: 0 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1197088964 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section home-fascia-intro-block\" id=\"section_1965785041\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-8230168\">\n\n\n\t<div id=\"col-520064188\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"title-high title1 c-nero-m\">Seguran\u00e7a em linhas de transporte de paletes &#8211; ReeR Spa<\/h2>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1662395077\">\n\n\n\t<div id=\"col-1205774432\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-4087778497\" class=\"text cutom-ul\">\n\t\t\n\n<h3 class=\"p1\">Prote\u00e7\u00e3o de uma linha de transporte de paletes com um paletizador de camadas e uma m\u00e1quina de empacotamento<\/h3>\n<p>A solicita\u00e7\u00e3o foi feita em rela\u00e7\u00e3o a uma linha de transporte de paletes com uma paletizadora de camadas capaz de empilhar caixas de diferentes alturas. A opera\u00e7\u00e3o automatizada \u00e9 bem estruturada e exige um alto n\u00edvel de prote\u00e7\u00e3o das \u00e1reas que podem representar um risco para os operadores.<\/p>\n<p>As caixas, que podem ter alturas diferentes, s\u00e3o carregadas em um transportador de rolos. Do transportador de roletes, elas passam para uma talha que levanta a caixa, gira-a 90\u00b0 e a direciona para a paletizadora de camadas, que empilha as caixas no palete. Depois disso, o palete completo com as caixas passa para a m\u00e1quina de empacotamento que aplica o filme de embalagem.<\/p>\n<p>Portanto, \u00e9 necess\u00e1ria uma solu\u00e7\u00e3o que reconhe\u00e7a as diferentes alturas das caixas, proteja a entrada da zona de risco (antes do elevador) e a abertura de sa\u00edda.<\/p>\n\t\t\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1965785041 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1552243536\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1917849935\">\n\n\n\t<div id=\"col-482207123\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"background-color:rgb(255, 255, 255);\"><\/div><\/div>\n\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"background-color:rgb(255, 255, 255);\"><\/div><\/div>\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_416341184\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"716\" height=\"378\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/palletizzatrice-con-bordo-1.webp\" class=\"attachment-original size-original\" alt=\"ReeR Spa solution for pallet transport lines\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/palletizzatrice-con-bordo-1.webp 716w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/palletizzatrice-con-bordo-1-300x158.webp 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/palletizzatrice-con-bordo-1-510x269.webp 510w\" sizes=\"(max-width: 716px) 100vw, 716px\" title=\"ReeR Spa solution for pallet transport lines\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_416341184 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1665939205\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3808255202\" class=\"text cutom-ul\">\n\t\t\n\n<h3 class=\"p1\">Solu\u00e7\u00f5es de seguran\u00e7a da ReeR Spa para paletizadoras de camadas<\/h3>\n<p>Para atender aos requisitos espec\u00edficos em termos de seguran\u00e7a, a ReeR Spa criou<\/p>\n<ul>\n<li><strong>Tr\u00eas fotoc\u00e9lulas<\/strong> que permitem a medi\u00e7\u00e3o da altura da caixa (A)<\/li>\n<li>Uma cortina de luz de seguran\u00e7a <strong>EOS 2<\/strong> (B) com resolu\u00e7\u00e3o de 90 mm para proteger a entrada da zona de risco e fun\u00e7\u00e3o de muting bidirecional (entrada e sa\u00edda) por meio de<strong> duas fotoc\u00e9lulas<\/strong> (M1 e M2)<\/li>\n<li>Uma segunda barreira de seguran\u00e7a <strong>EOS 2<\/strong> (C) com resolu\u00e7\u00e3o de 90 mm protegendo a passagem de sa\u00edda e fun\u00e7\u00e3o de muting unidirecional (somente sa\u00edda) por meio de <strong>duas fotoc\u00e9lulas<\/strong> (M3 e M4)<\/li>\n<\/ul>\n<p>Ambas as cortinas de luz de seguran\u00e7a EOS t\u00eam in\u00edcio\/rein\u00edcio autom\u00e1tico e uma altura controlada de 1060 mm.<\/p>\n<ul>\n<li>Para complementar isso e obter alta flexibilidade no gerenciamento do sistema de seguran\u00e7a, as barreiras e fotoc\u00e9lulas usadas como sensores de muting, chaves de seguran\u00e7a e paradas de emerg\u00eancia da m\u00e1quina s\u00e3o gerenciadas pelo <strong>controlador de seguran\u00e7a Mosaic M1 + m\u00f3dulo de expans\u00e3o MI802<\/strong>.<\/li>\n<\/ul>\n\t\t\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1552243536 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1653883412\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-643032632\">\n\n\n\t<div id=\"col-1438386249\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"p1\">Como funciona a prote\u00e7\u00e3o bidirecional com o EOS<\/h3>\n<p>As duas fotoc\u00e9lulas que desempenham a fun\u00e7\u00e3o de sensores de bloqueio s\u00e3o colocadas em ambos os lados em rela\u00e7\u00e3o \u00e0 barreira vertical. A ativa\u00e7\u00e3o da fun\u00e7\u00e3o Muting ocorre como resultado da interrup\u00e7\u00e3o simult\u00e2nea dos dois sensores em um tempo que pode ser programado por meio do par\u00e2metro Mosaic: Sensors Time (2 a 5 segundos).<\/p>\n<p>Enquanto os dois sensores permanecerem ocupados, a fun\u00e7\u00e3o Muting permanecer\u00e1. Ao liberar o primeiro dos dois sensores, a fun\u00e7\u00e3o de bloqueio \u00e9 desativada. A dura\u00e7\u00e3o m\u00e1xima da condi\u00e7\u00e3o de bloqueio \u00e9 program\u00e1vel por meio do par\u00e2metro Mosaic: Timeout (10 seg. a infinito).<\/p>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1510220311\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_71748777\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"305\" height=\"308\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/bidirezionale-muting.webp\" class=\"attachment-original size-original\" alt=\"Entry Exit Muting\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/bidirezionale-muting.webp 305w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/bidirezionale-muting-297x300.webp 297w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/bidirezionale-muting-150x150.webp 150w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/bidirezionale-muting-100x100.webp 100w\" sizes=\"(max-width: 305px) 100vw, 305px\" title=\"Entry Exit Muting\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_71748777 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1653883412 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_2018098261\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1556410267\">\n\n\n\t<div id=\"col-1189708961\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"title-high title2 c-nero-m\">Solu\u00e7\u00e3o ReeR<\/h2>\n<p>&nbsp;<\/p>\n<p class=\"fascia-intro-title-1 c-blue-m mb-0\">EOS2 Cortinas de luz de seguran\u00e7a<\/p>\n<div>A EOS2 \u00e9 uma gama compacta de cortinas de luz de seguran\u00e7a com desempenho competitivo e carater\u00edsticas inovadoras. Inclui modelos com fun\u00e7\u00f5es de seguran\u00e7a integradas, tais como sa\u00eddas est\u00e1ticas de auto-monitoriza\u00e7\u00e3o, controlo de contactores externos (EDM) e rein\u00edcio autom\u00e1tico ou manual selecion\u00e1vel.<\/div>\n<div>&nbsp;<\/div>\n<div>2 sa\u00eddas est\u00e1ticas PNP de seguran\u00e7a. F\u00e1cil liga\u00e7\u00e3o e instala\u00e7\u00e3o gra\u00e7as aos conectores M12 e \u00e0 utiliza\u00e7\u00e3o de cabos n\u00e3o blindados at\u00e9 100 metros.<\/div>\n<div class=\"row\"  id=\"row-111733112\">\n\n\n\t<div id=\"col-1163058161\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1553815634\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"400\" height=\"400\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2022\/12\/Fam_EOS2.png\" class=\"attachment-large size-large\" alt=\"EOS safety light curtain gamma\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2022\/12\/Fam_EOS2.png 400w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2022\/12\/Fam_EOS2-300x300.png 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2022\/12\/Fam_EOS2-150x150.png 150w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2022\/12\/Fam_EOS2-100x100.png 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" title=\"EOS safety light curtain gamma\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1553815634 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2026122171\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2461895618\" class=\"text cutom-ul\">\n\t\t\n\n<h3>EOS2<\/h3>\n<div>Para esta aplica\u00e7\u00e3o s\u00e3o utilizadas:<\/div>\n<div>&nbsp;<\/div>\n<ul>\n<li>Arranque\/Rein\u00edcio autom\u00e1tico<\/li>\n<li>Resolu\u00e7\u00e3o de 90 mm<\/li>\n<li>Liga\u00e7\u00f5es e configura\u00e7\u00f5es atrav\u00e9s de conectores M12 de 5 p\u00f3los. Podem ser utilizados cabos n\u00e3o blindados at\u00e9 100 metros de comprimento para ligar a cortina de luz.<\/li>\n<li>Alturas protegidas: 1060 mm<\/li>\n<\/ul>\n<p class=\"p1\"><a href=\"https:\/\/reer-stage.reersafety.com\/pt-pt\/categoria-produto\/cortinas-de-luz-de-seguranca\/eos2-cortinas-de-luz-de-seguranca\/?_gl=1*1r7xwaa*_up*MQ..*_ga*OTc5OTAwNDguMTcyOTYwMTQ1Nw..*_ga_4HF1BK8TQX*MTcyOTYwMTQ1Ni4xLjAuMTcyOTYwMTQ1Ni4wLjAuODA2MzY4NDAw*_ga_29E1L1E7HR*MTcyOTYwMTQ1Ni4xLjAuMTcyOTYwMTQ1Ni4wLjAuMzIxMTE4Nzk4*_ga_GBGDV2W82E*MTcyOTYwMTQ1Ni4xLjAuMTcyOTYwMTQ1Ni4wLjAuNDUyNzEzNTg3\" target=\"_blank\" rel=\"noopener\">Descobrir mais<\/a><\/p>\n\t\t\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2018098261 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(239, 240, 241);\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"background-color:rgb(255, 255, 255);\"><\/div><\/div>\n\n\t<section class=\"section\" id=\"section_1226270648\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-228457947\">\n\n\n\t<div id=\"col-278052560\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"p1\">Prote\u00e7\u00e3o unidirecional para sa\u00edda de paletes<\/h3>\n<p>As duas fotoc\u00e9lulas, que atuam como sensores de muting, s\u00e3o posicionadas na frente da \u00e1rea de sa\u00edda de paletes perigosos. A fun\u00e7\u00e3o de bloqueio \u00e9 ativada quando ambos os sensores s\u00e3o interrompidos simultaneamente em um per\u00edodo de tempo program\u00e1vel definido por meio do par\u00e2metro Mosaic: Sensor Time (de 2 a 5 segundos). A fun\u00e7\u00e3o Muting permanece ativa enquanto os dois sensores estiverem ocupados. Quando o primeiro dos dois sensores for liberado, o material transportado ter\u00e1 um tempo adicional program\u00e1vel definido por meio do par\u00e2metro Mosaic: End of Muting Time (de 2,5 a 6 segundos) &#8211; para deixar a \u00e1rea protegida delimitada pela cortina de luz de seguran\u00e7a.<\/p>\n<p>A condi\u00e7\u00e3o de muting ser\u00e1 desativada assim que a \u00e1rea protegida for liberada. Se a cortina de luz continuar ocupada, as sa\u00eddas de seguran\u00e7a ser\u00e3o desativadas, parando a m\u00e1quina.<\/p>\n<p>Para evitar que o sistema pare nos casos em que pe\u00e7as salientes ou oscila\u00e7\u00f5es do palete reocupem a cortina de luz ap\u00f3s o t\u00e9rmino da sequ\u00eancia de bloqueio, o Mosaic inclui a fun\u00e7\u00e3o Blind Time (de 250 milissegundos a 1 segundo). Esse par\u00e2metro permite que voc\u00ea defina por quanto tempo a cortina de luz pode ser reocupada ap\u00f3s o t\u00e9rmino da sequ\u00eancia de bloqueio sem disparar alarmes (m\u00e1ximo de 1 segundo).<\/p>\n<p>A dura\u00e7\u00e3o m\u00e1xima da condi\u00e7\u00e3o de muting pode ser programada usando o par\u00e2metro Mosaic: Timeout (de 10 segundos a infinito).<\/p>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-353103269\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"background-color:rgb(255, 255, 255);\"><\/div><\/div>\n\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"background-color:rgb(255, 255, 255);\"><\/div><\/div>\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1883479192\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"305\" height=\"308\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/monodirezionale-muting.webp\" class=\"attachment-original size-original\" alt=\"Only exit muting\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/monodirezionale-muting.webp 305w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/monodirezionale-muting-297x300.webp 297w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/monodirezionale-muting-150x150.webp 150w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/monodirezionale-muting-100x100.webp 100w\" sizes=\"(max-width: 305px) 100vw, 305px\" title=\"Only exit muting\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1883479192 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1226270648 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1165396492\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1116317639\">\n\n\n\t<div id=\"col-568625260\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"title-high title2 c-nero-m\">Solu\u00e7\u00e3o ReeR<\/h2>\n<p>&nbsp;<\/p>\n<p class=\"fascia-intro-title-1 c-blue-m mb-0\">Controladores e interfaces de seguran\u00e7a<\/p>\n<p>Mosaic is a safety hub able to manage all safety functions of machinery. Configurable and scalable, provides cost reductions and minimal wiring. <\/p>\n<div class=\"row\"  id=\"row-2104927538\">\n\n\n\t<div id=\"col-813143450\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_479464436\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"400\" height=\"480\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2021\/11\/MOSAIC_M1_00_TT.png\" class=\"attachment-original size-original\" alt=\"MOSAIC M1 main unit\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2021\/11\/MOSAIC_M1_00_TT.png 400w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2021\/11\/MOSAIC_M1_00_TT-250x300.png 250w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2021\/11\/MOSAIC_M1_00_TT-247x296.png 247w\" sizes=\"(max-width: 400px) 100vw, 400px\" title=\"MOSAIC M1 main unit\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_479464436 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1588590549\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-363009578\" class=\"text cutom-ul\">\n\t\t\n\n<h3>MOSAIC M1<\/h3>\n<ul>\n<li>8 entradas digitais<\/li>\n<li>2 pares OSSD (SIL 3)<\/li>\n<li>2 sa\u00eddas program\u00e1veis de sinaliza\u00e7\u00e3o<\/li>\n<li>4 sa\u00eddas de teste<\/li>\n<li>blocos terminais a parafusos<\/li>\n<\/ul>\n<p>Nesta aplica\u00e7\u00e3o, entradas\/sa\u00eddas adicionais s\u00e3o fornecidas pela unidade de expans\u00e3o MOSAIC MI802, com:<\/p>\n<ul>\n<li>8 entradas digitais<\/li>\n<li>2 entradas para Controlo de Arranque\/Rein\u00edcio e Rel\u00e9 Externo (EDM)<\/li>\n<li>2 pares de sa\u00eddas de seguran\u00e7a OSSD<\/li>\n<li>2 sa\u00eddas de estado<\/li>\n<li>4 sa\u00eddas de teste<\/li>\n<\/ul>\n<p><a href=\"https:\/\/reer-stage.reersafety.com\/pt-pt\/produto\/m1-1100000\/\" target=\"_blank\" rel=\"noopener\">Descobrir mais<\/a><\/p>\n\t\t\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1165396492 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(239, 240, 241);\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_2082934935\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1796505432\">\n\n\n\t<div id=\"col-846917343\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"is-divider divider clearfix\" style=\"background-color:rgb(255, 255, 255);\"><\/div>\n\n<p>Para garantir a m\u00e1xima seguran\u00e7a em suas linhas de transporte de paletes com paletizadores de camadas e m\u00e1quinas de embalagem, escolha a ReeR Spa.<\/p>\n<p>Nossas solu\u00e7\u00f5es de seguran\u00e7a oferecem prote\u00e7\u00e3o avan\u00e7ada, efici\u00eancia e flexibilidade operacional.<\/p>\n<p>Entre em contato conosco agora para descobrir como implementar um sistema de seguran\u00e7a sob medida para as suas necessidades de produ\u00e7\u00e3o.<\/p>\n<p><strong>ReeR, your future\u2019s safe!<\/strong><\/p>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1948707270\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"background-color:rgb(255, 255, 255);\"><\/div><\/div>\n\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"background-color:rgb(255, 255, 255);\"><\/div><\/div>\n\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"background-color:rgb(255, 255, 255);\"><\/div><\/div>\n\n\t<div id=\"text-512629855\" class=\"text\">\n\t\t\n\n\t\n\t<!--<a href=\"#\" data-open=\"#request-info-box\" class=\"button button-lg request-info-box-btn\">Solicite informa\u00e7\u00f5es<\/a>-->\n\t<a href=\"#request-info-box-1\" class=\"button primary is-large request-info-box-btn\"><span>Solicite informa\u00e7\u00f5es<\/span><\/a>\n\n\t<div id=\"request-info-box-1\" style=\"display: none\" class=\"_lightbox-content\">\n\t\t<iframe src=\"https:\/\/go.marketing.reersafety.com\/l\/895801\/2022-02-24\/xkn847?Articolo_Osservato=m%C3%A1quinas+paletizadoras+e+embaladoras\" frameborder=\"0\" width=\"100%\" height=\"680\" style=\"max-width: 550px\"><\/iframe>\t\t\n\t<\/div>\n\n\t\n\t\t\n<style>\n#text-512629855 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2082934935 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section landing-immagine-block\" id=\"section_297167068\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row immagine-row-content\"  id=\"row-1491816950\">\n\n\n\t<div id=\"col-785718609\" class=\"col block-content small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-1236921785\">\n\n\n\t<div id=\"col-160643477\" class=\"col col1 medium-12 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1101952613\">\n\t\t<a class=\"\" href=\"https:\/\/reer-stage.reersafety.com\/pt-pt\/produtos\/\"  >\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"1024\" height=\"558\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2023\/07\/banner-generico.webp\" class=\"attachment-original size-original\" alt=\"Prodotti ReeR\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2023\/07\/banner-generico.webp 1024w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2023\/07\/banner-generico-300x163.webp 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2023\/07\/banner-generico-768x419.webp 768w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2023\/07\/banner-generico-510x278.webp 510w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" title=\"Prodotti ReeR\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\n<style>\n#image_1101952613 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-528980129\" class=\"col col2 medium-12 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Seguran\u00e7a no local de trabalho \u00e9 essencial<\/h2>\n<h2>&nbsp;<\/h2>\n<p>Os dispositivos de seguran\u00e7a ReeR para prote\u00e7\u00e3o de m\u00e1quinas e sistemas industriais s\u00e3o projetados, projetados e fabricados na It\u00e1lia. As nossas solu\u00e7\u00f5es, garantidas pelo Sistema de Qualidade, certificado pela TUV Italia segundo a norma ISO 9001:2008, oferecem versatilidade e seguran\u00e7a a n\u00edvel internacional.<\/p>\n<p><a href=\"https:\/\/reer-stage.reersafety.com\/pt-pt\/produtos\/\"><strong>Descobrir mais<\/strong><\/a><\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_297167068 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":27273,"featured_media":917968,"parent":84775,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Seguran\u00e7a em m\u00e1quinas paletizadoras e embaladoras| ReeR<\/title>\n<meta name=\"description\" content=\"Descubra como melhorar a seguran\u00e7a nas m\u00e1quinas paletizadoras e embaladoras com as solu\u00e7\u00f5es de seguran\u00e7a da ReeR Spa.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seguran\u00e7a em m\u00e1quinas paletizadoras e embaladoras| ReeR\" \/>\n<meta property=\"og:description\" content=\"Descubra como melhorar a seguran\u00e7a nas m\u00e1quinas paletizadoras e embaladoras com as solu\u00e7\u00f5es de seguran\u00e7a da ReeR Spa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/\" \/>\n<meta property=\"og:site_name\" content=\"ReeR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T13:18:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/palletizzatrice-con-bordo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"716\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/\",\"url\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/\",\"name\":\"Seguran\u00e7a em m\u00e1quinas paletizadoras e embaladoras| ReeR\",\"isPartOf\":{\"@id\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/#website\"},\"datePublished\":\"2024-10-22T12:42:01+00:00\",\"dateModified\":\"2024-10-22T13:18:15+00:00\",\"description\":\"Descubra como melhorar a seguran\u00e7a nas m\u00e1quinas paletizadoras e embaladoras com as solu\u00e7\u00f5es de seguran\u00e7a da ReeR Spa.\",\"breadcrumb\":{\"@id\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/pagina-inicial\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aplica\u00e7\u00f5es\",\"item\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Planta de embalagem\",\"item\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"m\u00e1quinas paletizadoras e embaladoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/#website\",\"url\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/\",\"name\":\"ReeR\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reer-stage.reersafety.com\/pt-pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seguran\u00e7a em m\u00e1quinas paletizadoras e embaladoras| ReeR","description":"Descubra como melhorar a seguran\u00e7a nas m\u00e1quinas paletizadoras e embaladoras com as solu\u00e7\u00f5es de seguran\u00e7a da ReeR Spa.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"Seguran\u00e7a em m\u00e1quinas paletizadoras e embaladoras| ReeR","og_description":"Descubra como melhorar a seguran\u00e7a nas m\u00e1quinas paletizadoras e embaladoras com as solu\u00e7\u00f5es de seguran\u00e7a da ReeR Spa.","og_url":"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/","og_site_name":"ReeR","article_modified_time":"2024-10-22T13:18:15+00:00","og_image":[{"width":716,"height":378,"url":"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/10\/palletizzatrice-con-bordo.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/","url":"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/","name":"Seguran\u00e7a em m\u00e1quinas paletizadoras e embaladoras| ReeR","isPartOf":{"@id":"https:\/\/reer-stage.reersafety.com\/pt-pt\/#website"},"datePublished":"2024-10-22T12:42:01+00:00","dateModified":"2024-10-22T13:18:15+00:00","description":"Descubra como melhorar a seguran\u00e7a nas m\u00e1quinas paletizadoras e embaladoras com as solu\u00e7\u00f5es de seguran\u00e7a da ReeR Spa.","breadcrumb":{"@id":"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/solucao-de-seguranca-para-maquinas-paletizadoras-e-embaladoras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/reer-stage.reersafety.com\/pt-pt\/pagina-inicial\/"},{"@type":"ListItem","position":2,"name":"Aplica\u00e7\u00f5es","item":"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/"},{"@type":"ListItem","position":3,"name":"Planta de embalagem","item":"https:\/\/reer-stage.reersafety.com\/pt-pt\/aplicacoes\/planta-de-embalagem\/"},{"@type":"ListItem","position":4,"name":"m\u00e1quinas paletizadoras e embaladoras"}]},{"@type":"WebSite","@id":"https:\/\/reer-stage.reersafety.com\/pt-pt\/#website","url":"https:\/\/reer-stage.reersafety.com\/pt-pt\/","name":"ReeR","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reer-stage.reersafety.com\/pt-pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/reer-stage.reersafety.com\/pt-pt\/wp-json\/wp\/v2\/pages\/917919"}],"collection":[{"href":"https:\/\/reer-stage.reersafety.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/reer-stage.reersafety.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/reer-stage.reersafety.com\/pt-pt\/wp-json\/wp\/v2\/users\/27273"}],"replies":[{"embeddable":true,"href":"https:\/\/reer-stage.reersafety.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=917919"}],"version-history":[{"count":9,"href":"https:\/\/reer-stage.reersafety.com\/pt-pt\/wp-json\/wp\/v2\/pages\/917919\/revisions"}],"predecessor-version":[{"id":922748,"href":"https:\/\/reer-stage.reersafety.com\/pt-pt\/wp-json\/wp\/v2\/pages\/917919\/revisions\/922748"}],"up":[{"embeddable":true,"href":"https:\/\/reer-stage.reersafety.com\/pt-pt\/wp-json\/wp\/v2\/pages\/84775"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reer-stage.reersafety.com\/pt-pt\/wp-json\/wp\/v2\/media\/917968"}],"wp:attachment":[{"href":"https:\/\/reer-stage.reersafety.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=917919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}