{"id":229958,"date":"2024-08-06T15:29:07","date_gmt":"2024-08-06T13:29:07","guid":{"rendered":"https:\/\/www.reersafety.com\/applications\/automotive\/automatic-vehicle-classification-systems-toll-gates\/"},"modified":"2025-08-08T11:36:31","modified_gmt":"2025-08-08T09:36:31","slug":"sistemi-di-classificazione-veicoli-per-pedaggi-autostradali","status":"publish","type":"page","link":"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/","title":{"rendered":"Sistemi di classificazione  veicoli per pedaggi autostradali"},"content":{"rendered":"\n\n  <div class=\"banner has-hover inner-slider-block\" id=\"banner-1335262828\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n              <div class=\"height-fix is-invisible\"><img width=\"1920\" height=\"540\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/top-tool-gates.webp\" class=\"attachment-original size-original\" alt=\"top-tool-gates\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/top-tool-gates.webp 1920w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/top-tool-gates-300x84.webp 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/top-tool-gates-1024x288.webp 1024w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/top-tool-gates-768x216.webp 768w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/top-tool-gates-1536x432.webp 1536w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/top-tool-gates-510x143.webp 510w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"top-tool-gates\" \/><\/div>\n            \n<style>\n#banner-1335262828 .bg.bg-loaded {\n  background-image: url(https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/top-tool-gates.webp);\n}\n#banner-1335262828 {\n  background-color: rgb(255, 255, 255);\n}\n<\/style>\n  <\/div>\n\n\n\t<section class=\"section breadcrumb-section\" id=\"section_894869800\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1707498019\">\n\n\n\t<div id=\"col-1518382725\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div id=\"page-header-1677574004\" class=\"page-header-wrapper\">\n  <div class=\"page-title breadcrumb light simple-title\">\n\n    \n    <div class=\"page-title-inner container align-center flex-row medium-flex-wrap row-reverse\" >\n            <div class=\"title-content flex-col flex-left text-left medium-text-center\">\n        <div class=\"title-breadcrumbs pb-half pt-half\"><nav class=\"woocommerce-breadcrumb breadcrumbs uppercase\">Home<\/nav><\/div>      <\/div>\n    <\/div>\n\n       <\/div>\n    <\/div>\n  \n\n\n\t\t<\/div>\n\t\t\n<style>\n#col-1518382725 > .col-inner {\n  padding: 0 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_894869800 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section home-fascia-intro-block\" id=\"section_1731755061\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1698301562\">\n\n\n\t<div id=\"col-315577916\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"title-high title1 c-nero-m\">Sistemi di classificazione<br>\nveicoli per pedaggi autostradali<\/h2>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-659076637\">\n\n\n\t<div id=\"col-761103021\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1471734134\" class=\"text cutom-ul\">\n\t\t\n\n<p class=\"p1\">Utilizzo delle barriere opto-elettroniche nei sistemi per la riscossione pedaggi autostradali.<\/p>\n<p class=\"p1\">I metodi tipici per la riscossione dei pedaggi sui tratti stradali a pagamento sono:<\/p>\n<ul>\n<li class=\"p2\">La riscossione manuale &#8211; \u00c8 la forma pi\u00f9 semplice di riscossione dei pedaggi, in cui un esattore che opera da una cabina riscuote il pedaggio.<\/li>\n<li class=\"p2\">La riscossione automatica tramite distributori automatici &#8211; Consente la riscossione di diversi metodi di pagamento: monete, gettoni, tessere e carte di debito o di credito.<\/li>\n<li class=\"p2\">Il sistema di riscossione elettronica (ETC) &#8211; In grado di addebitare elettronicamente un pedaggio a un conto cliente stabilito.<\/li>\n<\/ul>\n<p class=\"p1\">In questa nota applicativa tratteremo due sottosistemi per il pagamento automatizzato dei pedaggi che utilizzano come sensori barriere di sicurezza e barriere di misura ReeR:<\/p>\n<ul>\n<li class=\"p2\">Il sottositema per la classificazione dei veicolo &#8211; Automatic Vehicle Classification System (AVC).<\/li>\n<li class=\"p2\">Il sottosistema per la riscossione elettronica &#8211; Electronic Toll Collection System (ETC)<\/li>\n<\/ul>\n\t\t\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1818801417\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_227307314\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"800\" height=\"485\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/toll-management-system.webp\" class=\"attachment-large size-large\" alt=\"Caselli autostradali\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/toll-management-system.webp 800w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/toll-management-system-300x182.webp 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/toll-management-system-768x466.webp 768w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/toll-management-system-510x309.webp 510w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"Caselli autostradali\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_227307314 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1731755061 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_782908309\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-15425344\">\n\n\n\t<div id=\"col-684019081\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1591099261\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"600\" height=\"660\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/classi_pedaggi_Ita.webp\" class=\"attachment-original size-original\" alt=\"Classi di pedaggio\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/classi_pedaggi_Ita.webp 600w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/classi_pedaggi_Ita-273x300.webp 273w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/classi_pedaggi_Ita-510x561.webp 510w\" sizes=\"(max-width: 600px) 100vw, 600px\" title=\"Classi di pedaggio\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1591099261 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-256604380\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-44891035\" class=\"text cutom-ul\">\n\t\t\n\n<p class=\"p1\">Per la <strong>Classificazione automatica dei veicoli (AVC)<\/strong> vengono utilizzati diversi tipi di sensori (laser, barriere optoelettroniche, infrarossi, telecamere e anelli di rilevamento intelligenti incorporati nella pavimentazione) installati nelle corsie di pedaggio.<\/p>\n<p class=\"p1\">Ad esempio, sulle tratte di Autostrade per l&#8217;Italia e sulla quasi totalit\u00e0 delle altre Concessionarie la classificazione dei veicoli viene effettuata sulla base di elementi fisicamente misurabili quali:<\/p>\n<ul>\n<li class=\"p2\">La sagoma &#8211; cio\u00e8 l&#8217;altezza del veicolo sulla perpendicolare dell&#8217;asse anteriore &#8211; Per i veicoli a 2 assi (classi A, B)<\/li>\n<li class=\"p2\">Il numero degli assi &#8211; Per i veicoli o convogli con pi\u00f9 di due assi (classi 3, 4, 5).<\/li>\n<\/ul>\n<p class=\"p1\">Classificazioni analoghe vengono utilizzati in altri paesi extra-europei come Cina, India.<\/p>\n\t\t\t<\/div>\n\t\n<p class=\"p1\"><strong>Electronic Toll Collection System (ETC)<\/strong> \u00e8 un sistema elettronico di pagamanto che rende possibili operazioni di pedaggio ad alta velocit\u00e0, poich\u00e9 i conducenti non devono fermarsi. L&#8217;ETC riduce inoltre la vulnerabilit\u00e0 finanziaria e le frodi, poich\u00e9 i pagamenti non richiedono la gestione di contanti.<\/p>\n<p class=\"p1\">Questo sistema comprende la codifica a barre, il pagamento online, l&#8217;elaborazione digitale dei pagamenti, l&#8217;RFID (identificazione a radiofrequenza), ecc.<\/p>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_782908309 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1456685916\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-68230662\">\n\n\n\t<div id=\"col-1774045784\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"p1\">Utilizzo delle barriere di misura Micron nei sistemi AVC<\/h3>\n<p class=\"p2\">In questo sistema per la classificazione automatica degli veicoli (realizzato in india dalla <strong>Metro Infrasys Pvt Ltd.<\/strong>) le barriere opto-elettroniche Micron vengoni utizzate per la rilevazione dei dati degli autoveicoli in transito e per la verifica incrociata dei pedaggi rilevati.<\/p>\n<div class=\"row\"  id=\"row-2031414055\">\n\n\n\t<div id=\"col-1645175305\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1748102067\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"1221\" height=\"527\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron_in-tool-gate-applicarion-2.webp\" class=\"attachment-original size-original\" alt=\"Applicazioni della barriera di misura Micron nei caselli autostradali - Esempio 1\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron_in-tool-gate-applicarion-2.webp 1221w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron_in-tool-gate-applicarion-2-300x129.webp 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron_in-tool-gate-applicarion-2-1024x442.webp 1024w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron_in-tool-gate-applicarion-2-768x331.webp 768w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron_in-tool-gate-applicarion-2-510x220.webp 510w\" sizes=\"(max-width: 1221px) 100vw, 1221px\" title=\"Applicazioni della barriera di misura Micron nei caselli autostradali &#8211; Esempio 1\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1748102067 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1045968622\">\n\n\n\t<div id=\"col-618175273\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2031043989\" class=\"text cutom-ul\">\n\t\t\n\n<p class=\"p1\">Quando il veicolo supera il varco, dopo il pagamento del pedaggio il sistema di classificazione automatica crea il profilo del veicolo e <br>automaticamente il software di gestione genera un rapporto per la verifica incrociata dei dati.<\/p>\n<p class=\"p1\">La barriera di misura Micron \u00e8 quindi un elemento chiave per la <br>valutazione della corretta tariffa di pedaggio in quanto garantisce un&#8217;accurata rilevazione e classificazione dei veicoli.<\/p>\n<p class=\"p1\">La barriera ottica permette di eseguire le rilevazioni e misure<br>seguenti:<\/p>\n<ul>\n<li class=\"p2\">Separazione veicoli &#8211; Rilevazione del singolo veicolo che attraversa la barriera<\/li>\n<li class=\"p2\">Conteggio degli assi di tipo ottico (conteggio assi dei veicoli)<\/li>\n<li class=\"p2\">Misurazione dell&#8217;altezza (rilevazione altezza sul primo asse)<\/li>\n<\/ul>\n<p class=\"p1\">L&#8217;affidabilit\u00e0 di questo sistema \u00e8 del 99,95% per veicoli<span class=\"Apple-converted-space\">&nbsp; <\/span>che transitano a 90 Km\/h, 99,00% per veicoli che transitano a 120 Km\/h.<\/p>\n<p class=\"p1\">La distanza minima di rilevazione dei veicoli \u00e8 di 10 mm tra veicoli attigui. Il sistema \u00e8 in grado rilevare il gancio traino.<\/p>\n<p class=\"p1\">Inoltre questo sitema con barriere opto-elettroniche di misura ha un design flessibile e supporta il cambiamento degli schemi di <br>classificazione.<\/p>\n<p class=\"p1\">La classificazione si basa su: assi, distanza tra assi, ruote singole e <br>doppie e altezze multiple del veicolo.<\/p>\n<p class=\"p1\">Le barriere Micron, poste al uscita di ogni corsia per il pagamento pedaggio, tramite l&#8217;interfaccia seriale RS 485 possono essere collegate ad un controller e trasmettere lo stato dei raggi:<\/p>\n<ul>\n<li class=\"p2\">FBO &#8211; Primo raggio occupato<\/li>\n<li class=\"p2\">LBO &#8211; Ultimo raggio occupato<\/li>\n<li class=\"p2\">CBO &#8211; Raggio centrale occupato *<\/li>\n<li class=\"p2\">NBO &#8211; Numero di raggi occupati<\/li>\n<li class=\"p2\">NCBO &#8211; Numero massimo di raggi consecutivi occupati *<\/li>\n<li class=\"p2\">BNO &#8211; Raggio numero non occupato<\/li>\n<\/ul>\n<p class=\"p1\">* Nel caso di pi\u00f9 zone occupate, i dati si riferiscono alla zona con il<span class=\"Apple-converted-space\">&nbsp; <\/span>maggior numero di raggi occupati.<\/p>\n\t\t\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1275046827\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1231098904\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"600\" height=\"1200\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron-Toll_gate-01.webp\" class=\"attachment-original size-original\" alt=\"Applicazioni della barriera di misura Micron nei caselli autostradali - Esempio 2\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron-Toll_gate-01.webp 600w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron-Toll_gate-01-150x300.webp 150w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron-Toll_gate-01-512x1024.webp 512w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/Micron-Toll_gate-01-510x1020.webp 510w\" sizes=\"(max-width: 600px) 100vw, 600px\" title=\"Applicazioni della barriera di misura Micron nei caselli autostradali &#8211; Esempio 2\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1231098904 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1456685916 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_671636194\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-826094591\">\n\n\n\t<div id=\"col-451476072\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"title-high title2 c-nero-m\">Soluzione ReeR<\/h2>\n<p>&nbsp;<\/p>\n<p class=\"fascia-intro-title-1 c-blue-m mb-0\">Micron barriera di misura e automazione<\/p>\n<p>Le&nbsp;<strong>barriere di misura<\/strong>&nbsp;sono&nbsp;<strong>barriere fotoelettriche<\/strong> per applicazioni industriali e civili dove \u00e8 necessario rilevare, misurare e riconoscere oggetti.<\/p>\n<div class=\"row\"  id=\"row-1912458952\">\n\n\n\t<div id=\"col-2091226152\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1974094114\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"400\" height=\"400\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/MICRON_400x400.webp\" class=\"attachment-original size-original\" alt=\"Barriere di misura MICRON\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/MICRON_400x400.webp 400w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/MICRON_400x400-300x300.webp 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/MICRON_400x400-150x150.webp 150w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/MICRON_400x400-100x100.webp 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" title=\"Barriere di misura MICRON\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1974094114 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1817890694\" class=\"col medium-1 small-12 large-1\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1271291501\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1904008148\" class=\"text cutom-ul\">\n\t\t\n\n<h3>Micron B<\/h3>\n<p class=\"p1\">Modelli MI B dotati di interfaccia seriale RS 485 con funzioni programmabili e 2 uscite digitali programmabili di tipo Push-pull. Ideale per misurazione dimensionale e rilevamento di profili e posizione di oggetti.<\/p>\n<ul>\n<li class=\"p1\">Altezze controllate: 150 mm &#8230; 3000 mm. Utilizzate le versioni superiori ai 2 m<\/li>\n<li class=\"p1\">Interfaccia di programmazione: interfaccia USB con connettore M5 a 4 poli.<\/li>\n<li class=\"p1\">Possibilit\u00e0 di collegare fino a 3 barriere Micron B come nodi di linea seriale RS 485 per il rilevamento simultaneo di pi\u00f9 dimensioni e misurazioni complesse.<\/li>\n<li class=\"p1\">Portata massima 10 m<\/li>\n<li class=\"p1\">Interasse tra i raggi in questa applicazione: 10 o 30 mm. L&#8217;intera gamma delle barriere Micron ha un interasse tra i raggi di 5 mm , 25 mm, 50 mm e 75 mm<\/li>\n<\/ul>\n<p><a href=\"https:\/\/reer-stage.reersafety.com\/it\/categoria-prodotto\/barriere-di-misura\/micron-barriere-di-misura\/usctia-seriale\/b-uscita-seriale-rs485\/\" target=\"_blank\" rel=\"noopener\">Maggiori informazioni<\/a><\/p>\n\t\t\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_671636194 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(239, 240, 241);\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_114150532\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-287823915\">\n\n\n\t<div id=\"col-1372211827\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3401304315\" class=\"text cutom-ul\">\n\t\t\n\n<h3 class=\"p1\">Utilizzo delle barriere di sicurezza EOS nei sistemi ETC<\/h3>\n<p class=\"p2\">Il sistema per la riscossione elettronica &#8211; Electronic Toll Collection System (ETC) utilizza:<\/p>\n<ul>\n<li class=\"p3\">Transponder (installati sugli autoveicoli)<\/li>\n<li class=\"p3\">Comunicazione wireless (Sensori RFID) per la lettura dei trasponder<\/li>\n<li class=\"p3\">Sensori sulla corsia di pagamento per il rilevamento del passaggio degli autoveicoli<\/li>\n<li class=\"p3\">Un sistema computerizzato (hardware e software) per l&#8217;identificazione univoca di ciascun veicolo, la riscossione elettronica del pedaggio, il monitoraggio generale del veicolo, del traffico e per la raccolta di dati<\/li>\n<\/ul>\n<p class=\"p2\">Le <strong>barriere di sicurezza EOS<\/strong> vengono utilizzate in questo caso come sensori per il rilevamento del passaggio del veicolo.<\/p>\n\t\t\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1442942020\">\n\n\n\t<div id=\"col-1750205271\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p class=\"p1\">Quando il veicolo passa attraverso l&#8217;area controllata dalla barriera di sicurezza, le uscite OSSD passano a livello logico basso indicando al sistema il passaggio di un veicolo. Questo attiver\u00e0 i sensori wireless RFID per la lettura del trasponder a bordo del veicolo; quindi l&#8217;identificazione dello stesso e la conseguente riscossione del pedaggio.&nbsp;<\/p>\n<p class=\"p1\">Il sistema per la lettura del trasponder funziona solamente se il veicolo transita ad una velocit\u00e0 inferiore a 40 Km\/h. Per controllare questa la velocit\u00e0 del veicolo viene utilizzata un altra coppia di barriere di sicurezza EOS. Viene controllato quanto tempo impiega il veicolo a transitare tra una barriera e l&#8217;altra e, in questo modo, controllata la velocit\u00e0.&nbsp;<\/p>\n<p class=\"p1\">Se il transito tra una barriera e l&#8217;altra avviene oltre il tempo stabilito (quindi velocit\u00e0 inferiore a 40 km\/h), le barriere attivano il sistema RFID per la lettura del&nbsp; trasponder. Se la velocit\u00e0 rilevata \u00e8 superiore a 40 Km\/h, non verr\u00e0 inviato il segnale di attivazione e di conseguenza il varco per il passaggio del veicolo rimarr\u00e0 chiuso. Un&#8217;apposita segnaletica dar\u00e0 indicazioni all&#8217;autista per dirigersi verso la corsia corretta.<\/p>\n<p class=\"p1\">In questa applicazione le barriere di sicurezza EOS sono poste all&#8217;ingresso della corsia di pedaggio per rilevare la presenza del veicolo e abilitare la lettura dello stato del trasponder sul veicolo. Questo rilevamento viene utilizzato dal Sistema ETC per dirigere il veicolo in avvicinamento all&#8217;appropriata corsia per la riscossione del pedaggio.<\/p>\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1433128076\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"600\" height=\"600\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-tool_gate-02.webp\" class=\"attachment-original size-original\" alt=\"Applicazioni della barriera di sicurezza EOS nei caselli autostradali - Esempio 1\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-tool_gate-02.webp 600w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-tool_gate-02-300x300.webp 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-tool_gate-02-150x150.webp 150w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-tool_gate-02-510x510.webp 510w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-tool_gate-02-100x100.webp 100w\" sizes=\"(max-width: 600px) 100vw, 600px\" title=\"Applicazioni della barriera di sicurezza EOS nei caselli autostradali &#8211; Esempio 1\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1433128076 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2070667368\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-744749816\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-744749816 {\n  padding-top: 25px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_19206292\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"600\" height=\"1200\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-Toll_gate-01.webp\" class=\"attachment-original size-original\" alt=\"Applicazioni della barriera di sicurezza EOS nei caselli autostradali - Esempio 1\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-Toll_gate-01.webp 600w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-Toll_gate-01-150x300.webp 150w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-Toll_gate-01-512x1024.webp 512w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2024\/08\/EOS-Toll_gate-01-510x1020.webp 510w\" sizes=\"(max-width: 600px) 100vw, 600px\" title=\"Applicazioni della barriera di sicurezza EOS nei caselli autostradali &#8211; Esempio 1\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_19206292 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_114150532 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1926234013\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1886323806\">\n\n\n\t<div id=\"col-263170321\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"title-high title2 c-nero-m\">Soluzione ReeR<\/h2>\n<p>&nbsp;<\/p>\n<p class=\"fascia-intro-title-1 c-blue-m mb-0\">Barriere di sicurezza EOS2<\/p>\n<p>EOS2 \u00e8 una gamma completa di barriere fotoelettriche di sicurezza compatte ad alte prestazioni per la protezione della maggior parte delle applicazioni industriali in Categoria 2. La gamma include modelli con l\u2019integrazione delle funzioni di sicurezza, tra cui l\u2019autocontrollo delle uscite statiche, il controllo dei contattori esterni (EDM). Funzione di Start\/Restart manuale o automatico selezionabile.<\/p>\n<p>2 uscite statiche PNP di sicurezza. Grande facilit\u00e0 di connessione ed installazione, grazie ai connettori M12 e all\u2019uso di cavi non schermati fino a 100 metri.<\/p>\n<div class=\"row\"  id=\"row-31842126\">\n\n\n\t<div id=\"col-433416845\" class=\"col medium-4 small-12 large-4\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_581344154\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"400\" height=\"400\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2022\/12\/Fam_EOS2.png\" class=\"attachment-large size-large\" alt=\"Barriere di sicurezza gamma EOS\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2022\/12\/Fam_EOS2.png 400w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2022\/12\/Fam_EOS2-300x300.png 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2022\/12\/Fam_EOS2-150x150.png 150w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2022\/12\/Fam_EOS2-100x100.png 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" title=\"Barriere di sicurezza gamma EOS\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_581344154 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1522768462\" class=\"col medium-1 small-12 large-1\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1763027440\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3402425018\" class=\"text cutom-ul\">\n\t\t\n\n<h3>EOS2<\/h3>\n<p class=\"p1\">Per questa applicaziomne vengono utilizzate delle barriere di sicurezza EOS2 903 A<\/p>\n<ul>\n<li class=\"p2\">Start\/Restart automatico<\/li>\n<li class=\"p2\">Risoluzione 30 mm<\/li>\n<li class=\"p2\">Connessione e configurazione tramite connettore M12 a 5 poli. Per il collegamento delle barriere possono essere utilizzati cavi non schermati con lunghezza fino a 100 metri.<\/li>\n<li class=\"p2\">Altezze protette: 160 mm &#8230; 2260 mm. In questa applicazione viene utilizzata una barriera con altezza protetta di 910 mm<\/li>\n<\/ul>\n<p class=\"p1\"><a href=\"https:\/\/reer-stage.reersafety.com\/it\/categoria-prodotto\/barriere-di-sicurezza\/eos2-barriere-di-sicurezza\/\" target=\"_blank\" rel=\"noopener\">Maggiori informazioni<\/a><\/p>\n\t\t\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1926234013 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(239, 240, 241);\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_352606588\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1049988785\">\n\n\n\t<div id=\"col-101148503\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1185574746\" class=\"text\">\n\t\t\n\n\t\n\t<!--<a href=\"#\" data-open=\"#request-info-box\" class=\"button button-lg request-info-box-btn\">Richiedi info<\/a>-->\n\t<a href=\"#request-info-box-1\" class=\"button primary is-large request-info-box-btn\"><span>Richiedi info<\/span><\/a>\n\n\t<div id=\"request-info-box-1\" style=\"display: none\" class=\"_lightbox-content\">\n\t\t<iframe src=\"https:\/\/go.marketing.reersafety.com\/l\/895801\/2022-02-24\/xkn7c7?Articolo_Osservato=Sistemi+di+classificazione++veicoli+per+pedaggi+autostradali\" frameborder=\"0\" width=\"100%\" height=\"680\" style=\"max-width: 550px\"><\/iframe>\t\t\n\t<\/div>\n\n\t\n\t\t\n<style>\n#text-1185574746 {\n  text-align: right;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-640616294\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><iframe loading=\"lazy\" title=\"EOS Video Product 2023\" src=\"https:\/\/player.vimeo.com\/video\/890236902?dnt=1&amp;app_id=122963\" width=\"1020\" height=\"574\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe><\/div>\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1506726167\">\n\n\n\t<div id=\"col-681924582\" class=\"col medium-8 small-12 large-8\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"video video-fit mb\" style=\"padding-top:56.25%;\"><p><iframe loading=\"lazy\" title=\"MICRON Video Product (ENG 2024)\" src=\"https:\/\/player.vimeo.com\/video\/988897619?dnt=1&amp;app_id=122963\" width=\"1020\" height=\"574\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe><\/p>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-703326871\" class=\"col medium-3 small-12 large-3\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t\n\t<!--<a href=\"#\" data-open=\"#request-info-box\" class=\"button button-lg request-info-box-btn\">Richiedi info<\/a>-->\n\t<a href=\"#request-info-box-2\" class=\"button primary is-large request-info-box-btn\"><span>Richiedi info<\/span><\/a>\n\n\t<div id=\"request-info-box-2\" style=\"display: none\" class=\"_lightbox-content\">\n\t\t<iframe src=\"https:\/\/go.marketing.reersafety.com\/l\/895801\/2022-02-24\/xkn7c7?Articolo_Osservato=Sistemi+di+classificazione++veicoli+per+pedaggi+autostradali\" frameborder=\"0\" width=\"100%\" height=\"680\" style=\"max-width: 550px\"><\/iframe>\t\t\n\t<\/div>\n\n\t\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_352606588 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1993760500\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-393359185\">\n\n\n\t<div id=\"col-2113079206\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_501794098\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img width=\"1020\" height=\"556\" src=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2023\/08\/banner-eos.webp\" class=\"attachment-large size-large\" alt=\"Prodotti EOS\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2023\/08\/banner-eos.webp 1024w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2023\/08\/banner-eos-300x163.webp 300w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2023\/08\/banner-eos-768x419.webp 768w, https:\/\/reer-stage.reersafety.com\/wp-content\/uploads\/2023\/08\/banner-eos-510x278.webp 510w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" title=\"Prodotti EOS\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_501794098 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2066730752\" class=\"col medium-6 small-12 large-6\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2 class=\"fascia-intro-title-2 c-blue-m mb-0\">EOS4<\/h2>\n<h3 class=\"h3 lead\">Barriere di Sicurezza per Applicazioni Industriali<\/h3>\n<p class=\"hide-for-medium\"><span style=\"color: #282828;\">Proteggi il personale e i tuoi impianti e macchinari in modo sicuro ed efficiente con le barriere fotoelettriche di sicurezza ReeR. La gamma delle soluzioni proposte copre ogni necessit\u00e0 di sicurezza nel campo dell\u2019automazione industriale. <\/span><\/p>\n<p class=\"hide-for-medium\"><span style=\"color: #282828;\"><strong>Le barriere fotoelettriche ReeR<\/strong> creano un campo protetto a infrarossi invisibile, consentendo la messa in sicurezza ottimale delle zone pericolose, inclusi ingressi e accessi. Grazie a questa soluzione, puoi garantire un ambiente di lavoro sicuro per il tuo personale, prevenendo incidenti e lesioni. <\/span><\/p>\n<p class=\"\"><a href=\"https:\/\/reer-stage.reersafety.com\/it\/categories\/barriere-di-sicurezza\/\"><strong>Scopri di pi\u00f9<\/strong><\/a><\/p>\n\n\t\t<\/div>\n\t\t\n<style>\n#col-2066730752 > .col-inner {\n  padding: 30px 30px 30px 30px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\n<style>\n#row-393359185 > .col > .col-inner {\n  background-color: rgb(239, 240, 241);\n}\n<\/style>\n<\/div>\n\t<div id=\"gap-1228253979\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1228253979 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1993760500 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":80200,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sistemi di classificazione veicoli per pedaggi autostradali | ReeR<\/title>\n<meta name=\"description\" content=\"Utilizzo delle barriere opto-elettroniche nei sistemi per la riscossione pedaggi. Barriere di misura Micron e barriere di sicurezza EOS\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistemi di classificazione veicoli per pedaggi autostradali | ReeR\" \/>\n<meta property=\"og:description\" content=\"Utilizzo delle barriere opto-elettroniche nei sistemi per la riscossione pedaggi. Barriere di misura Micron e barriere di sicurezza EOS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/\" \/>\n<meta property=\"og:site_name\" content=\"ReeR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-08T09:36:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/\",\"url\":\"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/\",\"name\":\"Sistemi di classificazione veicoli per pedaggi autostradali | ReeR\",\"isPartOf\":{\"@id\":\"https:\/\/reer-stage.reersafety.com\/it\/#website\"},\"datePublished\":\"2024-08-06T13:29:07+00:00\",\"dateModified\":\"2025-08-08T09:36:31+00:00\",\"description\":\"Utilizzo delle barriere opto-elettroniche nei sistemi per la riscossione pedaggi. Barriere di misura Micron e barriere di sicurezza EOS\",\"breadcrumb\":{\"@id\":\"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/reer-stage.reersafety.com\/it\/homepage\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Applicazioni\",\"item\":\"https:\/\/reer-stage.reersafety.com\/it\/applications\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Automotive\",\"item\":\"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sistemi di classificazione veicoli per pedaggi autostradali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reer-stage.reersafety.com\/it\/#website\",\"url\":\"https:\/\/reer-stage.reersafety.com\/it\/\",\"name\":\"ReeR\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reer-stage.reersafety.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistemi di classificazione veicoli per pedaggi autostradali | ReeR","description":"Utilizzo delle barriere opto-elettroniche nei sistemi per la riscossione pedaggi. Barriere di misura Micron e barriere di sicurezza EOS","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Sistemi di classificazione veicoli per pedaggi autostradali | ReeR","og_description":"Utilizzo delle barriere opto-elettroniche nei sistemi per la riscossione pedaggi. Barriere di misura Micron e barriere di sicurezza EOS","og_url":"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/","og_site_name":"ReeR","article_modified_time":"2025-08-08T09:36:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/","url":"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/","name":"Sistemi di classificazione veicoli per pedaggi autostradali | ReeR","isPartOf":{"@id":"https:\/\/reer-stage.reersafety.com\/it\/#website"},"datePublished":"2024-08-06T13:29:07+00:00","dateModified":"2025-08-08T09:36:31+00:00","description":"Utilizzo delle barriere opto-elettroniche nei sistemi per la riscossione pedaggi. Barriere di misura Micron e barriere di sicurezza EOS","breadcrumb":{"@id":"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/sistemi-di-classificazione-veicoli-per-pedaggi-autostradali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/reer-stage.reersafety.com\/it\/homepage\/"},{"@type":"ListItem","position":2,"name":"Applicazioni","item":"https:\/\/reer-stage.reersafety.com\/it\/applications\/"},{"@type":"ListItem","position":3,"name":"Automotive","item":"https:\/\/reer-stage.reersafety.com\/it\/applications\/automotive\/"},{"@type":"ListItem","position":4,"name":"Sistemi di classificazione veicoli per pedaggi autostradali"}]},{"@type":"WebSite","@id":"https:\/\/reer-stage.reersafety.com\/it\/#website","url":"https:\/\/reer-stage.reersafety.com\/it\/","name":"ReeR","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reer-stage.reersafety.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/reer-stage.reersafety.com\/it\/wp-json\/wp\/v2\/pages\/229958"}],"collection":[{"href":"https:\/\/reer-stage.reersafety.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/reer-stage.reersafety.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/reer-stage.reersafety.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/reer-stage.reersafety.com\/it\/wp-json\/wp\/v2\/comments?post=229958"}],"version-history":[{"count":13,"href":"https:\/\/reer-stage.reersafety.com\/it\/wp-json\/wp\/v2\/pages\/229958\/revisions"}],"predecessor-version":[{"id":1527880,"href":"https:\/\/reer-stage.reersafety.com\/it\/wp-json\/wp\/v2\/pages\/229958\/revisions\/1527880"}],"up":[{"embeddable":true,"href":"https:\/\/reer-stage.reersafety.com\/it\/wp-json\/wp\/v2\/pages\/80200"}],"wp:attachment":[{"href":"https:\/\/reer-stage.reersafety.com\/it\/wp-json\/wp\/v2\/media?parent=229958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}